
{"id":11478,"date":"2020-08-07T17:58:05","date_gmt":"2020-08-07T17:58:05","guid":{"rendered":"https:\/\/amnistia.org.mx\/contenido\/?p=11478"},"modified":"2020-08-07T17:58:06","modified_gmt":"2020-08-07T17:58:06","slug":"mujeres-indigenas-exigen-mayor-proteccion-en-la-lucha-de-decadas-por-sus-territorios-en-la-amazonia","status":"publish","type":"post","link":"https:\/\/amnistia.org.mx\/contenido\/index.php\/mujeres-indigenas-exigen-mayor-proteccion-en-la-lucha-de-decadas-por-sus-territorios-en-la-amazonia\/","title":{"rendered":"Mujeres ind\u00edgenas exigen mayor protecci\u00f3n en la lucha de d\u00e9cadas por sus territorios en la Amazon\u00eda"},"content":{"rendered":"\n<p>Las mujeres ind\u00edgenas ecuatorianas de la selva amaz\u00f3nica piden mayor protecci\u00f3n frente a las amenazas de muerte y los ataques, mientras contin\u00faan su lucha en defensa de sus tierras ancestrales.<\/p>\n\n\n\n<p>El colectivo Mujeres Amaz\u00f3nicas lleva muchos a\u00f1os protestando contra el saqueo de sus tierras por empresas petroleras, mineras y madereras. Cuentan con el apoyo de Amnist\u00eda Internacional, que, seg\u00fan la activista ambiental Patricia Gualinga (una de las portavoces del colectivo), lleva a\u00f1os ayudando a llamar la atenci\u00f3n del mundo sobre la campa\u00f1a de estas mujeres.<\/p>\n\n\n\n<p>\u201cDestruir la Amazon\u00eda es la destrucci\u00f3n del mundo\u201d \u2014dijo Gualinga a Amnist\u00eda Internacional en marzo\u2014. \u201cSi no se dan cuenta de eso, estamos perdidas\u201d.<\/p>\n\n\n\n<p><strong>Explotaci\u00f3n de tierras del pueblo Sarayaku<\/strong><\/p>\n\n\n\n<p>En 2002 y 2003, la petrolera argentina CGC irrumpi\u00f3 en el territorio del pueblo Sarayaku. Despleg\u00f3 guardias de seguridad militares y privados, construy\u00f3 carreteras y deforest\u00f3 terreno, destruyendo \u00e1rboles y plantas de gran valor ecol\u00f3gico, cultural y espiritual para la comunidad ind\u00edgena. Adem\u00e1s, como parte de sus operaciones de perforaci\u00f3n, la empresa enterr\u00f3 1,400 kilos de un explosivo llamado pentolita, en territorio de Sarayaku, poniendo en peligro la vida de sus habitantes y oblig\u00e1ndolos a abandonar parte de sus tierras ancestrales.<\/p>\n\n\n\n<p>\u201cEnterraron 50 cargas explosivas por la noche, y quienes lo hicieron sab\u00edan que era muy peligroso\u201d \u2014explica Gualinga\u2014. \u201cYo me vi obligada a ser una defensora de derechos humanos porque las petroleras violentaban los derechos de mi pueblo Sarayaku\u201d.<\/p>\n\n\n\n<p>En 2012, Amnist\u00eda Internacional ayud\u00f3 al pueblo Sarayaku a denunciar al Estado ecuatoriano ante la Corte Interamericana de Derechos Humanos (CoIDH), por haber autorizado a CGC a colocar explosivos y perforar sus tierras ancestrales en busca de petr\u00f3leo, sin contar con el consentimiento previo, libre e informado de la comunidad ind\u00edgena, y por no reparar los da\u00f1os ocasionados ni proteger a estas personas frente a abusos en el futuro.<\/p>\n\n\n\n<p>Ganaron la causa, y fue un triunfo hist\u00f3rico. La CoIDH fall\u00f3 en contra de Ecuador por violar el derecho a la integridad f\u00edsica de los miembros de la comunidad Sarayaku y poner en grave peligro su derecho a la vida.<\/p>\n\n\n\n<p>El tribunal resolvi\u00f3 asimismo que el gobierno ecuatoriano era responsable de violar el derecho de la comunidad Sarayaku a ser consultada, as\u00ed como su propiedad comunal y su identidad cultural.<\/p>\n\n\n\n<p>Sin embargo, a pesar de esta gran victoria, casi ocho a\u00f1os despu\u00e9s las autoridades no han acatado la sentencia de la CoIDH. Los explosivos contin\u00faan enterrados en territorio de Sarayaku y Patricia sigue sufriendo ataques y recibiendo amenazas de muerte.<\/p>\n\n\n\n<p>Gualinga afirma: \u201cLos explosivos est\u00e1n aqu\u00ed, y esto refleja lo que puede pasarles a otras comunidades si no perseveramos en la lucha. Debemos seguir presionando para que se cumpla todo lo que dispuso el tribunal. Porque sabemos que las empresas internacionales continuar\u00e1n haciendo lo posible por ignorarnos, y no podemos dejar que lo hagan\u201d.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"540\" height=\"360\" src=\" https:\/\/amnistia.org.mx\/contenido\/wp-content\/uploads\/2020\/08\/Foto_2_272199.jpg\" alt=\"\" class=\"wp-image-11482\"\/><\/figure><\/div>\n\n\n\n<p><strong>La uni\u00f3n hace la fuerza<\/strong><\/p>\n\n\n\n<p>Gualinga piensa que, a trav\u00e9s del movimiento de protesta de las mujeres, la uni\u00f3n hace la fuerza de las mujeres ind\u00edgenas. \u201cEn 2018 amenazaron con matarnos\u201d \u2014cuenta de sus agresores, a quienes las autoridades ecuatorianas no han identificado y llevado ante la justicia\u2014, \u201cy a algunas de mis compa\u00f1eras dirigentes les quemaron la casa hasta los cimientos. No fue una amenaza contra mi pueblo; fue una amenaza directa contra m\u00ed.\u201d<\/p>\n\n\n\n<p>\u201cPor definici\u00f3n, las mujeres corren mayor peligro que los hombres. Se las puede amenazar sexual y f\u00edsicamente; para los hombres es diferente. Las mujeres nos unimos porque tenemos que hacerlo, porque sabemos que juntas somos m\u00e1s fuertes y estamos m\u00e1s protegidas en m\u00faltiples niveles\u201d.<\/p>\n\n\n\n<p>\u201cAl agruparnos, nos protegemos. Esa es la raz\u00f3n de ser de Mujeres Amaz\u00f3nicas: no estar solas para no ser tan vulnerables\u201d.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"540\" height=\"360\" src=\" https:\/\/amnistia.org.mx\/contenido\/wp-content\/uploads\/2020\/08\/foto_3_272196.jpg\" alt=\"\" class=\"wp-image-11484\"\/><\/figure><\/div>\n\n\n\n<p>El 13 de noviembre de 2019, la comunidad Sarayaku present\u00f3 una demanda ante la Corte Constitucional de Ecuador para reclamar que las autoridades cumplieran lo dispuesto por la CoIDH en 2012. Y en marzo de 2020, Mujeres Amaz\u00f3nicas organiz\u00f3 una marcha multitudinaria de mujeres ind\u00edgenas por las calles de la capital, Quito, para entregar al gobierno ecuatoriano una petici\u00f3n de mayor protecci\u00f3n.<\/p>\n\n\n\n<p>El 19 de junio de 2020, la Corte Constitucional del Ecuador admiti\u00f3 la demanda, pero podr\u00eda tardar a\u00f1os en dictar sentencia. Desde marzo de 2020, la comunidad Sarayaku tambi\u00e9n se enfrenta a graves dificultades a causa de las inundaciones y, m\u00e1s recientemente, de la propagaci\u00f3n de la COVID-19 entre sus habitantes, que se suman a las que ya atravesaba esta remota comunidad de la selva tropical.<\/p>\n\n\n\n<p>\u201cSolamente piensan que los pueblos ind\u00edgenas est\u00e1n luchando porque violentan <em>nuestros<\/em> derechos\u201d \u2014afirma Gualinga\u2014, \u201cpero estamos luchando por el bienestar de <em>sus<\/em> hijos, que tienen tanto derecho como nosotros a respirar aire limpio. Luchamos para defender su ox\u00edgeno, el futuro de su planeta. Luchamos por su bienestar\u201d.<\/p>\n\n\n\n<p>Amnist\u00eda Internacional lleva muchos a\u00f1os apoyando a Mujeres Amaz\u00f3nicas y pide a las autoridades ecuatorianas que garanticen la protecci\u00f3n efectiva de defensores y defensoras de los derechos humanos como Patricia, para que puedan hacer o\u00edr su voz en condiciones seguras y continuar su labor de defensa de los derechos humanos sin miedo a sufrir represalias.<\/p>\n\n\n\n<p>Gualinga afirma que el apoyo de Amnist\u00eda Internacional al movimiento de protesta ha sido fundamental, porque ha sacado a relucir los rostros de las mujeres que luchan para defender la naturaleza y los derechos humanos. \u201cHemos servido de inspiraci\u00f3n a otras comunidades \u2014asegura\u2014, hemos permitido que mujeres marginadas alcen su voz y hemos obligado a petroleras a marcharse del pa\u00eds\u201d.<\/p>\n\n\n\n<p>\u201cTodo ello a costa de correr graves riesgos e invertir mucho tiempo y energ\u00eda. Merece la pena. Porque el planeta a\u00fan existe; porque la naturaleza est\u00e1 de nuestra parte. Y que el mundo sepa que la Amazon\u00eda es rica en biodiversidad, en cultura y en vida\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las mujeres ind\u00edgenas ecuatorianas de la selva amaz\u00f3nica piden mayor protecci\u00f3n frente a las amenazas de muerte y los ataques, mientras contin\u00faan su lucha en defensa de sus tierras ancestrales. &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mujeres-indigenas-exigen-mayor-proteccion-en-la-lucha-de-decadas-por-sus-territorios-en-la-amazonia\/\"> <span class=\"screen-reader-text\">Mujeres ind\u00edgenas exigen mayor protecci\u00f3n en la lucha de d\u00e9cadas por sus territorios en la Amazon\u00eda<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":4,"featured_media":11480,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[9],"tags":[40],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mujeres ind\u00edgenas exigen mayor protecci\u00f3n en la lucha de d\u00e9cadas por sus territorios en la Amazon\u00eda - amnistia.org.mx<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mujeres-indigenas-exigen-mayor-proteccion-en-la-lucha-de-decadas-por-sus-territorios-en-la-amazonia\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mujeres ind\u00edgenas exigen mayor protecci\u00f3n en la lucha de d\u00e9cadas por sus territorios en la Amazon\u00eda - amnistia.org.mx\" \/>\n<meta property=\"og:description\" content=\"Las mujeres ind\u00edgenas ecuatorianas de la selva amaz\u00f3nica piden mayor protecci\u00f3n frente a las amenazas de muerte y los ataques, mientras contin\u00faan su lucha en defensa de sus tierras ancestrales. &hellip; Mujeres ind\u00edgenas exigen mayor protecci\u00f3n en la lucha de d\u00e9cadas por sus territorios en la Amazon\u00eda Leer m\u00e1s &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mujeres-indigenas-exigen-mayor-proteccion-en-la-lucha-de-decadas-por-sus-territorios-en-la-amazonia\/\" \/>\n<meta property=\"og:site_name\" content=\"amnistia.org.mx\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-07T17:58:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-07T17:58:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amnistia.org.mx\/contenido\/wp-content\/uploads\/2020\/08\/Foto_1_272189.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/#website\",\"url\":\"https:\/\/amnistia.org.mx\/contenido\/\",\"name\":\"amnistia.org.mx\",\"description\":\"Nueva p\\u00e1gina de Amnist\\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/amnistia.org.mx\/contenido\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mujeres-indigenas-exigen-mayor-proteccion-en-la-lucha-de-decadas-por-sus-territorios-en-la-amazonia\/#primaryimage\",\"inLanguage\":\"es-MX\",\"url\":\"https:\/\/amnistia.org.mx\/contenido\/wp-content\/uploads\/2020\/08\/Foto_1_272189.jpg\",\"width\":540,\"height\":360,\"caption\":\"A group of Indigenous Ecuadorian women from the Amazon rainforest is calling for more protection from death threats and attacks as they continue to fight to defend their homelands.\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mujeres-indigenas-exigen-mayor-proteccion-en-la-lucha-de-decadas-por-sus-territorios-en-la-amazonia\/#webpage\",\"url\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mujeres-indigenas-exigen-mayor-proteccion-en-la-lucha-de-decadas-por-sus-territorios-en-la-amazonia\/\",\"name\":\"Mujeres ind\\u00edgenas exigen mayor protecci\\u00f3n en la lucha de d\\u00e9cadas por sus territorios en la Amazon\\u00eda - amnistia.org.mx\",\"isPartOf\":{\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mujeres-indigenas-exigen-mayor-proteccion-en-la-lucha-de-decadas-por-sus-territorios-en-la-amazonia\/#primaryimage\"},\"datePublished\":\"2020-08-07T17:58:05+00:00\",\"dateModified\":\"2020-08-07T17:58:06+00:00\",\"author\":{\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/#\/schema\/person\/7db421c495688267ce8ede4625c17fa5\"},\"breadcrumb\":{\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mujeres-indigenas-exigen-mayor-proteccion-en-la-lucha-de-decadas-por-sus-territorios-en-la-amazonia\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mujeres-indigenas-exigen-mayor-proteccion-en-la-lucha-de-decadas-por-sus-territorios-en-la-amazonia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mujeres-indigenas-exigen-mayor-proteccion-en-la-lucha-de-decadas-por-sus-territorios-en-la-amazonia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/\",\"url\":\"https:\/\/amnistia.org.mx\/contenido\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mujeres-indigenas-exigen-mayor-proteccion-en-la-lucha-de-decadas-por-sus-territorios-en-la-amazonia\/\",\"url\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mujeres-indigenas-exigen-mayor-proteccion-en-la-lucha-de-decadas-por-sus-territorios-en-la-amazonia\/\",\"name\":\"Mujeres ind\\u00edgenas exigen mayor protecci\\u00f3n en la lucha de d\\u00e9cadas por sus territorios en la Amazon\\u00eda\"}}]},{\"@type\":[\"Person\"],\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/#\/schema\/person\/7db421c495688267ce8ede4625c17fa5\",\"name\":\"Alejandro Ju\\u00e1rez Gamero\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/#personlogo\",\"inLanguage\":\"es-MX\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e312d5566d1c3ffb56f86415d6f0e606?s=96&d=mm&r=g\",\"caption\":\"Alejandro Ju\\u00e1rez Gamero\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/posts\/11478"}],"collection":[{"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/comments?post=11478"}],"version-history":[{"count":3,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/posts\/11478\/revisions"}],"predecessor-version":[{"id":11487,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/posts\/11478\/revisions\/11487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/media\/11480"}],"wp:attachment":[{"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/media?parent=11478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/categories?post=11478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/tags?post=11478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}