
{"id":34052,"date":"2024-09-20T13:37:48","date_gmt":"2024-09-20T18:37:48","guid":{"rendered":"https:\/\/amnistia.org.mx\/contenido\/?p=34052"},"modified":"2024-09-20T13:39:51","modified_gmt":"2024-09-20T18:39:51","slug":"strongglobal-secretaria-general-de-amnistia-insta-a-lideres-y-lideresas-a-aprovechar-oportunidad-historica-en-las-naciones-unidas-strong","status":"publish","type":"post","link":"https:\/\/amnistia.org.mx\/contenido\/index.php\/strongglobal-secretaria-general-de-amnistia-insta-a-lideres-y-lideresas-a-aprovechar-oportunidad-historica-en-las-naciones-unidas-strong\/","title":{"rendered":"<strong>Global: La secretaria general de Amnist\u00eda insta a los l\u00edderes y lideresas mundiales a aprovechar una oportunidad hist\u00f3rica en la Asamblea General de las Naciones Unidas<\/strong>"},"content":{"rendered":"\n<p>La secretaria general de Amnist\u00eda Internacional, Agn\u00e8s Callamard, estar\u00e1 en Nueva York para la apertura del debate general de alto nivel del 79 per\u00edodo de sesiones de la Asamblea General de las Naciones Unidas y participar\u00e1 en la Cumbre del Futuro.<\/p>\n\n\n\n<p>Del 20 al 24 de septiembre conceder\u00e1 entrevistas en la ciudad de Nueva York en las que responder\u00e1 a cuestiones relacionadas con el propio desarrollo de la Asamblea General de las Naciones Unidas, as\u00ed como sobre los conflictos en curso en Gaza, Sud\u00e1n y Ucrania. Su art\u00edculo de opini\u00f3n sobre la Cumbre del Futuro, \u201c<a href=\"https:\/\/www.amnesty.org\/es\/latest\/news\/2024\/09\/we-must-act-globally-to-safeguard-the-future-of-humanity\/\" target=\"_blank\" rel=\"noreferrer noopener\">Debemos actuar globalmente para salvaguardar el futuro de la Humanidad<\/a>\u201d, se ha publicado recientemente en <a href=\"https:\/\/www.newsweek.com\/we-must-act-now-safeguard-future-humanity-opinion-1952214\" target=\"_blank\" rel=\"noreferrer noopener\">Newsweek.<\/a><\/p>\n\n\n\n<p>\u201cLa Asamblea General de este a\u00f1o y la Cumbre del Futuro se presentan como una oportunidad hist\u00f3rica para que los l\u00edderes y lideresas mundiales tracen el rumbo hacia un mundo m\u00e1s seguro, justo y ecol\u00f3gico. Para alcanzar este ambicioso objetivo se requieren compromisos firmes y una mentalidad audaz. Los l\u00edderes mundiales deben preguntarse si la reuni\u00f3n en Nueva York va a ser simplemente otra cita en la que hablar sobre una mayor cooperaci\u00f3n y consenso, o si van a mostrar la imaginaci\u00f3n y la convicci\u00f3n que se requieren para que se produzcan realmente. Las m\u00faltiples crisis que asuelan el mundo, la creciente emergencia clim\u00e1tica y la ruptura del orden multilateral dejan cada vez menos margen para que los l\u00edderes y lideresas reconozcan estos problemas y tomen medidas colectivas para solucionarlos por el bien com\u00fan de la humanidad. Me estremezco al pensar en las consecuencias que tendr\u00eda desaprovechar esta oportunidad. Nuestro futuro colectivo est\u00e1 en juego\u201d, ha declarado Agn\u00e8s Callamard.<\/p>\n\n\n\n<p>\u201cPara Amnist\u00eda Internacional, s\u00f3lo hay un camino aceptable hacia el futuro: el que se construye sobre los derechos humanos universales e indivisibles. Adem\u00e1s, s\u00f3lo hay un destino aceptable: la dignidad igual y sostenible de todas las personas como titulares de derechos\u201d.<\/p>\n\n\n\n<p>Agn\u00e8s Callamard mantendr\u00e1 varias reuniones con representantes gubernamentales y defensores y defensoras de los derechos humanos. Hablar\u00e1 sobre la necesidad de dar voz a la sociedad civil en los foros intergubernamentales (\u201cUNMuting\u201d), sobre la importancia de fomentar la gobernanza inclusiva y participativa y sobre la necesidad de una reforma fiscal global y una econom\u00eda basada en los derechos que ofrezca un futuro sostenible.<\/p>\n\n\n\n<p>Est\u00e1 disponible para debatir sobre estas y otras cuestiones prioritarias, incluida la consolidaci\u00f3n de pr\u00e1cticas autoritarias en pa\u00edses como T\u00fanez y Venezuela; la necesidad de una regulaci\u00f3n m\u00e1s estricta de las nuevas tecnolog\u00edas que representan una amenaza para los derechos humanos; la mediocre respuesta global a la crisis clim\u00e1tica y el empeoramiento de la devastaci\u00f3n ambiental; y la implacable guerra contra las mujeres, desde los ataques al derecho al aborto hasta la opresi\u00f3n y discriminaci\u00f3n sist\u00e9micas que se ejercen contra ellas en Afganist\u00e1n e Ir\u00e1n.<\/p>\n\n\n\n<p><strong>Informaci\u00f3n complementaria<\/strong><\/p>\n\n\n\n<p>El 79 periodo de sesiones de la Asamblea General de las Naciones Unidas comienza el 10 de septiembre y concluye a finales de diciembre de 2024. Incluye la Cumbre del Futuro, en la que los d\u00edas 22 y 23 de septiembre los l\u00edderes y lideresas mundiales se reunir\u00e1n para abordar las dificultades cr\u00edticas y las brechas de gobernanza mundial que han puesto de relieve las recientes crisis mundiales.<\/p>\n\n\n\n<p>Esta Cumbre tiene como objetivo reafirmar los compromisos con los Objetivos de Desarrollo Sostenible y la Carta de las Naciones Unidas, as\u00ed como mejorar la cooperaci\u00f3n y sentar las bases para un sistema multilateral revitalizado a trav\u00e9s de la negociaci\u00f3n de un Pacto para el Futuro orientado a la acci\u00f3n.<\/p>\n\n\n\n<p>Agn\u00e8s Callamard es secretaria general de Amnist\u00eda Internacional. Dirige el trabajo de la organizaci\u00f3n en defensa de los derechos humanos y es su principal portavoz. Es una figura destacada del panorama de los derechos humanos desde hace decenios. En 2016 fue elegida relatora especial de la ONU sobre las ejecuciones extrajudiciales, sumarias o arbitrarias. Compagin\u00f3 su labor en la ONU con el cargo de directora del proyecto Global Freedom of Expression de la Universidad de Columbia en Nueva York. Anteriormente se desempe\u00f1\u00f3 como directora ejecutiva de la ONG Article 19, dedicada a la libertad de expresi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La secretaria general de Amnist\u00eda Internacional, Agn\u00e8s Callamard, estar\u00e1 en Nueva York para la apertura del debate general de alto nivel del 79 per\u00edodo de sesiones de la Asamblea General &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/amnistia.org.mx\/contenido\/index.php\/strongglobal-secretaria-general-de-amnistia-insta-a-lideres-y-lideresas-a-aprovechar-oportunidad-historica-en-las-naciones-unidas-strong\/\"> <span class=\"screen-reader-text\"><strong>Global: La secretaria general de Amnist\u00eda insta a los l\u00edderes y lideresas mundiales a aprovechar una oportunidad hist\u00f3rica en la Asamblea General de las Naciones Unidas<\/strong><\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":4,"featured_media":34053,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[9],"tags":[],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Global: La secretaria general de Amnist\u00eda insta a los l\u00edderes y lideresas mundiales a aprovechar una oportunidad hist\u00f3rica en la Asamblea General de las Naciones Unidas - amnistia.org.mx<\/title>\n<meta name=\"description\" content=\"La secretaria general de Amnist\u00eda Internacional, Agn\u00e8s Callamard, insta a los l\u00edderes y lideresas de la ONU a trazar un rumbo m\u00e1s seguro para el mundo.\" \/>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amnistia.org.mx\/contenido\/index.php\/strongglobal-secretaria-general-de-amnistia-insta-a-lideres-y-lideresas-a-aprovechar-oportunidad-historica-en-las-naciones-unidas-strong\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Global: La secretaria general de Amnist\u00eda insta a los l\u00edderes y lideresas mundiales a aprovechar una oportunidad hist\u00f3rica en la Asamblea General de las Naciones Unidas - amnistia.org.mx\" \/>\n<meta property=\"og:description\" content=\"La secretaria general de Amnist\u00eda Internacional, Agn\u00e8s Callamard, insta a los l\u00edderes y lideresas de la ONU a trazar un rumbo m\u00e1s seguro para el mundo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amnistia.org.mx\/contenido\/index.php\/strongglobal-secretaria-general-de-amnistia-insta-a-lideres-y-lideresas-a-aprovechar-oportunidad-historica-en-las-naciones-unidas-strong\/\" \/>\n<meta property=\"og:site_name\" content=\"amnistia.org.mx\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-20T18:37:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-20T18:39:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amnistia.org.mx\/contenido\/wp-content\/uploads\/2024\/09\/Foto-ajustada-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"385\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/#website\",\"url\":\"https:\/\/amnistia.org.mx\/contenido\/\",\"name\":\"amnistia.org.mx\",\"description\":\"Nueva p\\u00e1gina de Amnist\\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/amnistia.org.mx\/contenido\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/strongglobal-secretaria-general-de-amnistia-insta-a-lideres-y-lideresas-a-aprovechar-oportunidad-historica-en-las-naciones-unidas-strong\/#primaryimage\",\"inLanguage\":\"es-MX\",\"url\":\"https:\/\/amnistia.org.mx\/contenido\/wp-content\/uploads\/2024\/09\/Foto-ajustada-3.jpg\",\"width\":800,\"height\":385},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/strongglobal-secretaria-general-de-amnistia-insta-a-lideres-y-lideresas-a-aprovechar-oportunidad-historica-en-las-naciones-unidas-strong\/#webpage\",\"url\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/strongglobal-secretaria-general-de-amnistia-insta-a-lideres-y-lideresas-a-aprovechar-oportunidad-historica-en-las-naciones-unidas-strong\/\",\"name\":\"Global: La secretaria general de Amnist\\u00eda insta a los l\\u00edderes y lideresas mundiales a aprovechar una oportunidad hist\\u00f3rica en la Asamblea General de las Naciones Unidas - amnistia.org.mx\",\"isPartOf\":{\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/strongglobal-secretaria-general-de-amnistia-insta-a-lideres-y-lideresas-a-aprovechar-oportunidad-historica-en-las-naciones-unidas-strong\/#primaryimage\"},\"datePublished\":\"2024-09-20T18:37:48+00:00\",\"dateModified\":\"2024-09-20T18:39:51+00:00\",\"author\":{\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/#\/schema\/person\/b858cccf2e25328bf3ae12e197ab7f75\"},\"description\":\"La secretaria general de Amnist\\u00eda Internacional, Agn\\u00e8s Callamard, insta a los l\\u00edderes y lideresas de la ONU a trazar un rumbo m\\u00e1s seguro para el mundo.\",\"breadcrumb\":{\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/strongglobal-secretaria-general-de-amnistia-insta-a-lideres-y-lideresas-a-aprovechar-oportunidad-historica-en-las-naciones-unidas-strong\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/amnistia.org.mx\/contenido\/index.php\/strongglobal-secretaria-general-de-amnistia-insta-a-lideres-y-lideresas-a-aprovechar-oportunidad-historica-en-las-naciones-unidas-strong\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/strongglobal-secretaria-general-de-amnistia-insta-a-lideres-y-lideresas-a-aprovechar-oportunidad-historica-en-las-naciones-unidas-strong\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/\",\"url\":\"https:\/\/amnistia.org.mx\/contenido\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/strongglobal-secretaria-general-de-amnistia-insta-a-lideres-y-lideresas-a-aprovechar-oportunidad-historica-en-las-naciones-unidas-strong\/\",\"url\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/strongglobal-secretaria-general-de-amnistia-insta-a-lideres-y-lideresas-a-aprovechar-oportunidad-historica-en-las-naciones-unidas-strong\/\",\"name\":\"Global: La secretaria general de Amnist\\u00eda insta a los l\\u00edderes y lideresas mundiales a aprovechar una oportunidad hist\\u00f3rica en la Asamblea General de las Naciones Unidas\"}}]},{\"@type\":[\"Person\"],\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/#\/schema\/person\/b858cccf2e25328bf3ae12e197ab7f75\",\"name\":\"Alejandro Ju\\u00e1rez Gamero\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/#personlogo\",\"inLanguage\":\"es-MX\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e312d5566d1c3ffb56f86415d6f0e606?s=96&d=mm&r=g\",\"caption\":\"Alejandro Ju\\u00e1rez Gamero\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/posts\/34052"}],"collection":[{"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/comments?post=34052"}],"version-history":[{"count":3,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/posts\/34052\/revisions"}],"predecessor-version":[{"id":34056,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/posts\/34052\/revisions\/34056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/media\/34053"}],"wp:attachment":[{"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/media?parent=34052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/categories?post=34052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/tags?post=34052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}