
{"id":43012,"date":"2026-05-05T13:58:58","date_gmt":"2026-05-05T18:58:58","guid":{"rendered":"https:\/\/amnistia.org.mx\/contenido\/?p=43012"},"modified":"2026-05-12T18:32:03","modified_gmt":"2026-05-12T23:32:03","slug":"mensaje-a-la-fifa-y-paises-anfitriones-de-la-copa-mundial","status":"publish","type":"post","link":"https:\/\/amnistia.org.mx\/contenido\/index.php\/mensaje-a-la-fifa-y-paises-anfitriones-de-la-copa-mundial\/","title":{"rendered":"Dile a la FIFA y a los pa\u00edses anfitriones de la Copa Mundial: sin miedo, sin represi\u00f3n, sin excusas"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"43012\" class=\"elementor elementor-43012\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c44876f elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"c44876f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-503da4a\" data-id=\"503da4a\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c71073f elementor-widget__width-initial animated-fast elementor-widget-tablet__width-initial e-transform elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c71073f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;,&quot;_animation_delay&quot;:900,&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><span class=\"elementor-heading-title elementor-size-default\"><span style=\"background: ; color: unset; padding: 0.02em 0.2em; white-space: true;\"> FIRMA LA<\/span><\/span>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d8c1e6 elementor-widget__width-initial animated-fast elementor-widget-tablet__width-initial e-transform elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"9d8c1e6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;,&quot;_animation_delay&quot;:900,&quot;_transform_translateX_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<span class=\"elementor-heading-title elementor-size-default\"><span style=\"background: ; color: unset; padding: 0.02em 0.2em; white-space: true;\"> PETICI\u00d3N<\/span><\/span>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8139287 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"8139287\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dile a la FIFA y a los pa\u00edses anfitriones de la Copa Mundial: sin miedo, sin represi\u00f3n, sin excusas <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b48c0c0 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b48c0c0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<h4 id=\"h-israel-esta-cometiendo-con-impunidad-violaciones-atroces-del-derecho-internacional-contra-la-poblacion-palestina-y-en-libano-y-acaba-de-adoptar-una-ley-de-pena-de-muerte-dirigida-a-la-poblacion-palestina-la-union-europea-ue-es-el-mayor-socio-comercial-de-israel-y-debe-tomar-medidas-concretas-italia-y-alemania-pueden-influir-en-la-decision-de-suspender-el-acuerdo-comercial-entre-la-ue-e-israel-envia-un-mensaje-y-exige-a-giorgia-meloni-y-a-friedrich-merz-que-dejen-de-dar-luz-verde-al-genocidio-la-ocupacion-ilegal-y-el-apartheid-de-israel\" class=\"wp-block-heading\"><strong><span class=\"TextRun SCXW123417103 BCX8\" lang=\"ES\" xml:lang=\"ES\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW123417103 BCX8\">Los ataques a los derechos y libertades est\u00e1n convirtiendo un festival de alegr\u00eda en uno de terror. Exige algo mejor. Dile al presidente de la FIFA Gianni Infantino y a las autoridades de los pa\u00edses anfitriones que hagan de esta Copa Mundial un evento para todas las personas.<\/span><\/span><span class=\"EOP Selected SCXW123417103 BCX8\" data-ccp-props=\"{&quot;134245417&quot;:false,&quot;201341983&quot;:2,&quot;335559739&quot;:246,&quot;335559740&quot;:240}\">\u00a0<\/span><\/strong><\/h4>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d27a056 elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"d27a056\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1l es el problema?\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27a2bab elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget-tablet__width-initial elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"27a2bab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span data-contrast=\"none\">Cada cuatro a\u00f1os, miles de millones de personas hablan el mismo idioma: el del f\u00fatbol. Culturas radicalmente diferentes. Un espect\u00e1culo compartido. No importa si eres de Brasil o de Hait\u00ed, tu aspecto ni a qui\u00e9n amas. La Copa Mundial une a la gente como ning\u00fan otro evento. Eso es el f\u00fatbol. Es lo que la humanidad puede ser.<\/span><span data-ccp-props=\"{&quot;134245417&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Sin embargo, ese sue\u00f1o compartido est\u00e1 amenazado. A medida que se acerca el torneo, las autoridades de Estados Unidos, M\u00e9xico y Canad\u00e1 contin\u00faan<\/span><span data-contrast=\"auto\">\u00a0<\/span><span data-contrast=\"auto\">poniendo en el punto de mira<\/span><span data-contrast=\"none\">\u00a0a las personas migrantes, restringiendo las protestas y ocultando a las comunidades ya marginadas para que no se las vea.\u00a0<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;201341983&quot;:2,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:246,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">S\u00f3lo en 2025, el gobierno de Trump deport\u00f3 a m\u00e1s de 500.000 personas \u2014m\u00e1s de seis veces el n\u00famero de personas que asistir\u00e1n a la final de la Copa Mundial\u2014 y agentes de inmigraci\u00f3n mataron a migrantes, manifestantes y observadores.<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;201341983&quot;:2,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:246,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81c91fc elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget-tablet__width-initial elementor-hidden-desktop elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"81c91fc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span data-contrast=\"none\">Cada cuatro a\u00f1os, miles de millones de personas hablan el mismo idioma: el del f\u00fatbol. Culturas radicalmente diferentes. Un espect\u00e1culo compartido. No importa si eres de Brasil o de Hait\u00ed, tu aspecto ni a qui\u00e9n amas. La Copa Mundial une a la gente como ning\u00fan otro evento. Eso es el f\u00fatbol. Es lo que la humanidad puede ser.<\/span><span data-ccp-props=\"{&quot;134245417&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c5f989b\" data-id=\"c5f989b\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3155ce8 elementor-align-center elementor-widget elementor-widget-lottie\" data-id=\"3155ce8\" data-element_type=\"widget\" data-settings=\"{&quot;source_json&quot;:{&quot;url&quot;:&quot; https:\\\/\\\/amnistia.org.mx\\\/contenido\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/42905-sign-icon.json&quot;,&quot;id&quot;:20708,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;loop&quot;:&quot;yes&quot;,&quot;play_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.5,&quot;sizes&quot;:[]},&quot;source&quot;:&quot;media_file&quot;,&quot;caption_source&quot;:&quot;none&quot;,&quot;link_to&quot;:&quot;none&quot;,&quot;trigger&quot;:&quot;arriving_to_viewport&quot;,&quot;viewport&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;start_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;0&quot;,&quot;sizes&quot;:[]},&quot;end_point&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;100&quot;,&quot;sizes&quot;:[]},&quot;renderer&quot;:&quot;svg&quot;}\" data-widget_type=\"lottie.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.11.7 - 22-03-2023 *\/\n.e-lottie__container{display:inline-block;max-width:var(--lottie-container-max-width);width:var(--lottie-container-width);opacity:var(--lottie-container-opacity)}.e-lottie__container:hover{opacity:var(--lottie-container-opacity-hover);transition-duration:var(--lottie-container-transition-duration-hover)}.e-lottie__container svg,.e-lottie__container svg *{transition:none!important}.e-lottie__caption{color:var(--caption-color);margin-top:var(--caption-margin-top);text-align:var(--caption-text-align)}<\/style><div class=\"e-lottie__container\"><div class=\"e-lottie__animation\"><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5adc80 elementor-widget elementor-widget-menu-anchor\" data-id=\"f5adc80\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\nbody.elementor-page .elementor-widget-menu-anchor{margin-bottom:0}<\/style>\t\t<div id=\"FIRMAR\" class=\"elementor-menu-anchor\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b136bd elementor-widget__width-inherit elementor-widget-tablet__width-initial elementor-widget elementor-widget-html\" data-id=\"2b136bd\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\n.if{ \n    }\n.marco{}\n    <\/style>\n    \n<div class=\"marco\">\n<iframe loading=\"lazy\" class=\"if\" src=\"https:\/\/amnistia.org.mx\/peticiones\/fifa2026\/\" width=\"100%\" height=\"953\"  scrolling=\"no\" ><\/iframe>\n\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c5b518 elementor-section-height-min-height elementor-section-items-stretch elementor-section-full_width elementor-section-stretched elementor-section-height-default\" data-id=\"1c5b518\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a0d117f\" data-id=\"a0d117f\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1ef851 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-heading\" data-id=\"c1ef851\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1l es el problema?\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a78a42f elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget-tablet__width-initial elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"a78a42f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span data-contrast=\"none\">Cada cuatro a\u00f1os, miles de millones de personas hablan el mismo idioma: el del f\u00fatbol. Culturas radicalmente diferentes. Un espect\u00e1culo compartido. No importa si eres de Brasil o de Hait\u00ed, tu aspecto ni a qui\u00e9n amas. La Copa Mundial une a la gente como ning\u00fan otro evento. Eso es el f\u00fatbol. Es lo que la humanidad puede ser.<\/span><span data-ccp-props=\"{&quot;134245417&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Sin embargo, ese sue\u00f1o compartido est\u00e1 amenazado. A medida que se acerca el torneo, las autoridades de Estados Unidos, M\u00e9xico y Canad\u00e1 contin\u00faan<\/span><span data-contrast=\"auto\">\u00a0<\/span><span data-contrast=\"auto\">poniendo en el punto de mira<\/span><span data-contrast=\"none\">\u00a0a las personas migrantes, restringiendo las protestas y ocultando a las comunidades ya marginadas para que no se las vea.\u00a0<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;201341983&quot;:2,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:246,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fce90d elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget-tablet__width-initial elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"4fce90d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span data-contrast=\"none\">En M\u00e9xico, la movilizaci\u00f3n de las fuerzas armadas pone en riesgo a manifestantes pac\u00edficos. En Canad\u00e1, a las personas sin hogar se las margina m\u00e1s de lo que ya est\u00e1n. En los tres pa\u00edses anfitriones, la hinchada LGBTQI+ sufre discriminaci\u00f3n, violencia y hostigamiento.\u00a0<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;201341983&quot;:2,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:246,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1730610 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget-tablet__width-initial elementor-hidden-desktop elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"1730610\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span data-contrast=\"none\">Sin embargo, ese sue\u00f1o compartido est\u00e1 amenazado. A medida que se acerca el torneo, las autoridades de Estados Unidos, M\u00e9xico y Canad\u00e1 contin\u00faan<\/span><span data-contrast=\"auto\">\u00a0<\/span><span data-contrast=\"auto\">poniendo en el punto de mira<\/span><span data-contrast=\"none\">\u00a0a las personas migrantes, restringiendo las protestas y ocultando a las comunidades ya marginadas para que no se las vea.\u00a0<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;201341983&quot;:2,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:246,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">S\u00f3lo en 2025, el gobierno de Trump deport\u00f3 a m\u00e1s de 500.000 personas \u2014m\u00e1s de seis veces el n\u00famero de personas que asistir\u00e1n a la final de la Copa Mundial\u2014 y agentes de inmigraci\u00f3n mataron a migrantes, manifestantes y observadores.<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;201341983&quot;:2,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:246,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">En M\u00e9xico, la movilizaci\u00f3n de las fuerzas armadas pone en riesgo a manifestantes pac\u00edficos. En Canad\u00e1, a las personas sin hogar se las margina m\u00e1s de lo que ya est\u00e1n. En los tres pa\u00edses anfitriones, la hinchada LGBTQI+ sufre discriminaci\u00f3n, violencia y hostigamiento.\u00a0<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;201341983&quot;:2,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:246,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79b4d00 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"79b4d00\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"495\" src=\"https:\/\/amnistia.org.mx\/contenido\/wp-content\/uploads\/2026\/04\/EU-ASSOCIATION-WEB-BANNER-1024x495.jpg\" class=\"attachment-large size-large wp-image-42881\" alt=\"\u00a9 Anadolu via Getty Images\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">\u00a9 Anadolu via Getty Images<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bcc2bc elementor-widget elementor-widget-heading\" data-id=\"2bcc2bc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lo que deber\u00eda ser una celebraci\u00f3n global puede convertirse en un festival de terror.  <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42c8474 elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"42c8474\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<section class=\"article has-sidebar\"><article class=\"article-content is-narrow\" aria-labelledby=\"article-title\"><section class=\"article has-sidebar\"><article class=\"article-content is-narrow\" aria-labelledby=\"article-title\"><p><span data-contrast=\"none\">Esta situaci\u00f3n debe terminar. La hinchada y las comunidades locales deben poder celebrar libremente. La FIFA prometi\u00f3 un torneo en el que todo el mundo se sienta seguro, incluido y libre de ejercer sus derechos, pero la represi\u00f3n y la divisi\u00f3n amenazan con ocupar un lugar central.<\/span><span data-ccp-props=\"{&quot;134245417&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">El presidente de la FIFA Gianni Infantino y las autoridades de los pa\u00edses anfitriones deben actuar ya.\u00a0<\/span><b><span data-contrast=\"none\">La Copa Mundial nos pertenece a todos y todas: es hora de cumplir esa promesa.<\/span><\/b><span data-ccp-props=\"{&quot;134245417&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p><\/article><\/section><\/article><\/section>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e580b5 elementor-widget elementor-widget-heading\" data-id=\"1e580b5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfC\u00f3mo puedes ayudar?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea5f8fd elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"ea5f8fd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<section class=\"article has-sidebar\"><article class=\"article-content is-narrow\" aria-labelledby=\"article-title\"><section class=\"article has-sidebar\"><article class=\"article-content is-narrow\" aria-labelledby=\"article-title\"><p><span data-contrast=\"none\">Env\u00eda un mensaje al presidente de la FIFA Gianni Infantino y a las autoridades de los pa\u00edses anfitriones: que respeten las protestas pac\u00edficas, pongan fin a las detenciones y deportaciones masivas y protejan a todas las personas de la discriminaci\u00f3n.<\/span><span data-ccp-props=\"{&quot;335551550&quot;:6,&quot;335551620&quot;:6}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Miedo o libertad. Divisi\u00f3n o unidad. Crueldad o humanidad.\u00a0<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;201341983&quot;:2,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:246,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p><p><span data-contrast=\"none\">Nosotros y nosotras elegimos. Y elegimos oponer resistencia.\u00a0<\/span><span data-contrast=\"none\">La\u00a0humanidad\u00a0debe\u00a0triunfar.<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false,&quot;201341983&quot;:2,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:246,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p><\/article><\/section><\/article><\/section>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-022dc83 e-con-boxed e-flex e-con\" data-id=\"022dc83\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-092107c e-con-full e-flex e-con\" data-id=\"092107c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7027fea elementor-widget elementor-widget-text-editor\" data-id=\"7027fea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56df62b9 animated-fast elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading animated fadeInUp\" data-id=\"56df62b9\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"theme-post-title.default\"><div class=\"elementor-widget-container\">INFORME<\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69ae63d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"69ae63d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La humanidad debe triunfar:<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcfff91 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"bcfff91\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56df62b9 animated-fast elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading animated fadeInUp\" data-id=\"56df62b9\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"theme-post-title.default\"><div class=\"elementor-widget-container\"><p class=\"elementor-heading-title elementor-size-default\">Defender los derechos y abordar la represi\u00f3n en la Copa Mundial de la FIFA 2026<\/p><\/div><\/div><p class=\"elementor-element elementor-element-fe74fbd elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"fe74fbd\" data-element_type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6668386 elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6668386\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1cd3cd elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"e1cd3cd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"entry-content wp-block-post-content is-layout-flow wp-block-post-content-is-layout-flow\"><p>La Copa Mundial de la FIFA 2026 se celebra en medio de una aguda crisis de derechos humanos, con considerables riesgos para la afici\u00f3n, los jugadores, los periodistas, los trabajadores y trabajadoras y las comunidades locales.<\/p><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d5fb40 elementor-widget elementor-widget-button\" data-id=\"3d5fb40\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/amnistia.org.mx\/contenido\/index.php\/la-humanidad-debe-triunfar-defender-los-derechos-y-abordar-la-represion-en-la-copa-mundial-de-la-fifa-2026\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">DESCARGA AQU\u00cd<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c735e48 e-con-full elementor-hidden-mobile e-flex e-con\" data-id=\"c735e48\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eeccd06 elementor-widget elementor-widget-image\" data-id=\"eeccd06\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/amnistia.org.mx\/contenido\/wp-content\/uploads\/2026\/05\/Informe_Portada_Rompiendo_El_Tejido_Social_20032026-1-1024x576.png\" class=\"attachment-large size-large wp-image-43019\" alt=\"Un estudiante de la Universidad Jesuita de Guadalajara (ITESO) coloca una vela cerca de una r\u00e9plica del trofeo de la Copa Mundial de la FIFA decorada con fotos de personas desaparecidas, durante una intervenci\u00f3n art\u00edstica con el colectivo &quot;Luz y Esperanza&quot; en Guadalajara, Jalisco, M\u00e9xico, el 21 de noviembre de 2025. M\u00e9xico ser\u00e1 uno de los tres pa\u00edses anfitriones de la Copa Mundial 2026, y Jalisco albergar\u00e1 partidos de clasificaci\u00f3n. (Foto de ULISES RUIZ \/ AFP v\u00eda Getty Images)\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Un estudiante de la Universidad Jesuita de Guadalajara (ITESO) coloca una vela cerca de una r\u00e9plica del trofeo de la Copa Mundial de la FIFA decorada con fotos de personas desaparecidas, durante una intervenci\u00f3n art\u00edstica con el colectivo \"Luz y Esperanza\" en Guadalajara, Jalisco, M\u00e9xico, el 21 de noviembre de 2025. M\u00e9xico ser\u00e1 uno de los tres pa\u00edses anfitriones de la Copa Mundial 2026, y Jalisco albergar\u00e1 partidos de clasificaci\u00f3n. (Foto de ULISES RUIZ \/ AFP v\u00eda Getty Images)<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e7089d3 e-con-boxed e-flex e-con\" data-id=\"e7089d3\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7112537 e-con-full e-flex e-con\" data-id=\"7112537\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-b052a9b e-con-boxed e-flex e-con\" data-id=\"b052a9b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d666c79 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"d666c79\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">COMUNICADOS Y NOTICIAS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aacee01 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"aacee01\" data-element_type=\"widget\" data-settings=\"{&quot;pagination_type&quot;:&quot;numbers&quot;,&quot;classic_columns&quot;:&quot;3&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/amnistia.org.mx\/contenido\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-posts.min.css\">\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-42977 post type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-fifa2026 tag-global\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/amnistia.org.mx\/contenido\/index.php\/gianni-infantino-debe-aprovechar-su-discurso-ante-el-congreso-de-la-fifa-para-comprometerse-con-una-copa-mundial-sin-deportaciones-detenciones-ni-represion\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"768\" height=\"371\" src=\"https:\/\/amnistia.org.mx\/contenido\/wp-content\/uploads\/2026\/04\/315639-2-1468x710-1.jpg\" class=\"attachment-medium_large size-medium_large wp-image-42978\" alt=\"\" loading=\"lazy\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/amnistia.org.mx\/contenido\/index.php\/gianni-infantino-debe-aprovechar-su-discurso-ante-el-congreso-de-la-fifa-para-comprometerse-con-una-copa-mundial-sin-deportaciones-detenciones-ni-represion\/\" >\n\t\t\t\tGianni Infantino debe aprovechar su discurso ante el congreso de la FIFA para comprometerse con una Copa Mundial sin deportaciones, detenciones ni represi\u00f3n\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tabril 30, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u00a9 AFP or licensors \u201cEl presidente de la FIFA, Gianni Infantino, debe decirles a las asociaciones miembros que se re\u00fanen ma\u00f1ana en el 76\u00ba. Congreso de la FIFA en Vancouver<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/amnistia.org.mx\/contenido\/index.php\/gianni-infantino-debe-aprovechar-su-discurso-ante-el-congreso-de-la-fifa-para-comprometerse-con-una-copa-mundial-sin-deportaciones-detenciones-ni-represion\/\" aria-label=\"Read more about Gianni Infantino debe aprovechar su discurso ante el congreso de la FIFA para comprometerse con una Copa Mundial sin deportaciones, detenciones ni represi\u00f3n\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-42575 post type-post status-publish format-standard has-post-thumbnail hentry category-noticias tag-fifa2026 tag-global\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/amnistia.org.mx\/contenido\/index.php\/global-la-fifa-y-los-paises-anfitriones-de-la-copa-mundial-deben-impedir-que-el-torneo-se-convierta-en-una-amenaza-para-la-aficion-y-las-comunidades\/\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"768\" height=\"493\" src=\"https:\/\/amnistia.org.mx\/contenido\/wp-content\/uploads\/2026\/03\/Foto-2.jpg\" class=\"attachment-medium_large size-medium_large wp-image-42576\" alt=\"\" loading=\"lazy\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/amnistia.org.mx\/contenido\/index.php\/global-la-fifa-y-los-paises-anfitriones-de-la-copa-mundial-deben-impedir-que-el-torneo-se-convierta-en-una-amenaza-para-la-aficion-y-las-comunidades\/\" >\n\t\t\t\t<strong>Global: La FIFA y los pa\u00edses anfitriones de la Copa Mundial deben impedir que el torneo se convierta en una amenaza para la afici\u00f3n y las comunidades<\/strong>\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tmarzo 30, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>&nbsp;Adjuntos del sheriff del condado de Hennepin detienen a una persona manifestante frente al edificio federal Bishop Henry Whipple durante una protesta contra las operaciones del Servicio de Inmigraci\u00f3n y<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/amnistia.org.mx\/contenido\/index.php\/global-la-fifa-y-los-paises-anfitriones-de-la-copa-mundial-deben-impedir-que-el-torneo-se-convierta-en-una-amenaza-para-la-aficion-y-las-comunidades\/\" aria-label=\"Read more about &lt;strong&gt;Global: La FIFA y los pa\u00edses anfitriones de la Copa Mundial deben impedir que el torneo se convierta en una amenaza para la afici\u00f3n y las comunidades&lt;\/strong&gt;\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8da23db e-con-boxed e-flex e-con\" data-id=\"8da23db\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46cbb06 elementor-widget elementor-widget-text-editor\" data-id=\"46cbb06\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32fd921 e-con-full elementor-hidden-mobile e-flex e-con\" data-id=\"32fd921\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-257be83 e-con-full e-flex e-con\" data-id=\"257be83\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc1b054 elementor-widget elementor-widget-template\" data-id=\"cc1b054\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"41374\" class=\"elementor elementor-41374\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ea72a26 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"ea72a26\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22e9edfb\" data-id=\"22e9edfb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4715cd72 elementor-widget elementor-widget-heading\" data-id=\"4715cd72\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">PUEDES HACER M\u00c1S<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64abd90e e-con-full e-flex e-con\" data-id=\"64abd90e\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7803df3e elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7803df3e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">En Amnist\u00eda Internacional trabajamos para exponer las <strong>violaciones de los derechos humanos<\/strong>, dando una luz de esperanza a quienes a\u00fan esperan justicia. Con tu apoyo, podemos hacer realidad los derechos humanos universales.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2dac45b0 e-con-boxed e-flex e-con\" data-id=\"2dac45b0\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2abab9ff elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2abab9ff\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/amnistia.org.mx\/contenido\/index.php\/dona\/\" class=\"elementor-button-link elementor-button elementor-size-xl elementor-animation-grow\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00a1QUIERO DONAR!<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e286287 e-con-full elementor-hidden-desktop elementor-hidden-tablet e-flex e-con\" data-id=\"e286287\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-d394522 e-con-boxed e-flex e-con\" data-id=\"d394522\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fdadd39 elementor-widget elementor-widget-template\" data-id=\"fdadd39\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"41374\" class=\"elementor elementor-41374\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ea72a26 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"ea72a26\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22e9edfb\" data-id=\"22e9edfb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4715cd72 elementor-widget elementor-widget-heading\" data-id=\"4715cd72\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">PUEDES HACER M\u00c1S<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64abd90e e-con-full e-flex e-con\" data-id=\"64abd90e\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7803df3e elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7803df3e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">En Amnist\u00eda Internacional trabajamos para exponer las <strong>violaciones de los derechos humanos<\/strong>, dando una luz de esperanza a quienes a\u00fan esperan justicia. Con tu apoyo, podemos hacer realidad los derechos humanos universales.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2dac45b0 e-con-boxed e-flex e-con\" data-id=\"2dac45b0\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2abab9ff elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2abab9ff\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/amnistia.org.mx\/contenido\/index.php\/dona\/\" class=\"elementor-button-link elementor-button elementor-size-xl elementor-animation-grow\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00a1QUIERO DONAR!<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>A miles de millones de personas les encanta la Copa Mundial, pero las deportaciones, la discriminaci\u00f3n anti-LGBTI+ y la represi\u00f3n la est\u00e1n convirtiendo en un festival de terror. Dile a la FIFA que act\u00fae ya. <\/p>\n","protected":false},"author":18,"featured_media":42881,"comment_status":"closed","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[322,10],"tags":[40,28],"acf":[],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dile a la FIFA y a los pa\u00edses anfitriones de la Copa Mundial: sin miedo, sin represi\u00f3n, sin excusas - amnistia.org.mx<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mensaje-a-la-fifa-y-paises-anfitriones-de-la-copa-mundial\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dile a la FIFA y a los pa\u00edses anfitriones de la Copa Mundial: sin miedo, sin represi\u00f3n, sin excusas - amnistia.org.mx\" \/>\n<meta property=\"og:description\" content=\"A miles de millones de personas les encanta la Copa Mundial, pero las deportaciones, la discriminaci\u00f3n anti-LGBTI+ y la represi\u00f3n la est\u00e1n convirtiendo en un festival de terror. Dile a la FIFA que act\u00fae ya.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mensaje-a-la-fifa-y-paises-anfitriones-de-la-copa-mundial\/\" \/>\n<meta property=\"og:site_name\" content=\"amnistia.org.mx\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-05T18:58:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T23:32:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amnistia.org.mx\/contenido\/wp-content\/uploads\/2026\/04\/EU-ASSOCIATION-WEB-BANNER.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1468\" \/>\n\t<meta property=\"og:image:height\" content=\"710\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/#website\",\"url\":\"https:\/\/amnistia.org.mx\/contenido\/\",\"name\":\"amnistia.org.mx\",\"description\":\"Nueva p\\u00e1gina de Amnist\\u00eda\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/amnistia.org.mx\/contenido\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mensaje-a-la-fifa-y-paises-anfitriones-de-la-copa-mundial\/#primaryimage\",\"inLanguage\":\"es-MX\",\"url\":\"https:\/\/amnistia.org.mx\/contenido\/wp-content\/uploads\/2026\/04\/EU-ASSOCIATION-WEB-BANNER.jpg\",\"width\":1468,\"height\":710,\"caption\":\"\\u00a9 Anadolu via Getty Images\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mensaje-a-la-fifa-y-paises-anfitriones-de-la-copa-mundial\/#webpage\",\"url\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mensaje-a-la-fifa-y-paises-anfitriones-de-la-copa-mundial\/\",\"name\":\"Dile a la FIFA y a los pa\\u00edses anfitriones de la Copa Mundial: sin miedo, sin represi\\u00f3n, sin excusas - amnistia.org.mx\",\"isPartOf\":{\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mensaje-a-la-fifa-y-paises-anfitriones-de-la-copa-mundial\/#primaryimage\"},\"datePublished\":\"2026-05-05T18:58:58+00:00\",\"dateModified\":\"2026-05-12T23:32:03+00:00\",\"author\":{\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/#\/schema\/person\/d2f786357f75df54423772c307a57fa2\"},\"breadcrumb\":{\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mensaje-a-la-fifa-y-paises-anfitriones-de-la-copa-mundial\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mensaje-a-la-fifa-y-paises-anfitriones-de-la-copa-mundial\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mensaje-a-la-fifa-y-paises-anfitriones-de-la-copa-mundial\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/\",\"url\":\"https:\/\/amnistia.org.mx\/contenido\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mensaje-a-la-fifa-y-paises-anfitriones-de-la-copa-mundial\/\",\"url\":\"https:\/\/amnistia.org.mx\/contenido\/index.php\/mensaje-a-la-fifa-y-paises-anfitriones-de-la-copa-mundial\/\",\"name\":\"Dile a la FIFA y a los pa\\u00edses anfitriones de la Copa Mundial: sin miedo, sin represi\\u00f3n, sin excusas\"}}]},{\"@type\":[\"Person\"],\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/#\/schema\/person\/d2f786357f75df54423772c307a57fa2\",\"name\":\"Fernanda Jim\\u00e9nez Aguilar\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/amnistia.org.mx\/contenido\/#personlogo\",\"inLanguage\":\"es-MX\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/adfb626108fbdf0cbe48df94696b5411?s=96&d=mm&r=g\",\"caption\":\"Fernanda Jim\\u00e9nez Aguilar\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/posts\/43012"}],"collection":[{"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/comments?post=43012"}],"version-history":[{"count":36,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/posts\/43012\/revisions"}],"predecessor-version":[{"id":43096,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/posts\/43012\/revisions\/43096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/media\/42881"}],"wp:attachment":[{"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/media?parent=43012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/categories?post=43012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amnistia.org.mx\/contenido\/index.php\/wp-json\/wp\/v2\/tags?post=43012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}